{"id":12224,"count":1,"description":"","link":"https:\/\/www.crazycrow.com\/site\/tag\/kentucky-blacksmith-weekend\/","name":"Kentucky Blacksmith Weekend","slug":"kentucky-blacksmith-weekend","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kentucky Blacksmith Weekend Archives - Crazy Crow Trading Post<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.crazycrow.com\/site\/tag\/kentucky-blacksmith-weekend\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kentucky Blacksmith Weekend Archives - Crazy Crow Trading Post\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.crazycrow.com\/site\/tag\/kentucky-blacksmith-weekend\/\" \/>\n<meta property=\"og:site_name\" content=\"Crazy Crow Trading Post\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.crazycrow.com\\\/site\\\/tag\\\/kentucky-blacksmith-weekend\\\/\",\"url\":\"https:\\\/\\\/www.crazycrow.com\\\/site\\\/tag\\\/kentucky-blacksmith-weekend\\\/\",\"name\":\"Kentucky Blacksmith Weekend Archives - Crazy Crow Trading Post\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.crazycrow.com\\\/site\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.crazycrow.com\\\/site\\\/tag\\\/kentucky-blacksmith-weekend\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.crazycrow.com\\\/site\\\/tag\\\/kentucky-blacksmith-weekend\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.crazycrow.com\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kentucky Blacksmith Weekend\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.crazycrow.com\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/www.crazycrow.com\\\/site\\\/\",\"name\":\"Crazy Crow Trading Post\",\"description\":\"World&#039;s Largest Supplier of Native American and Mountain Man Crafts and Supplies\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.crazycrow.com\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kentucky Blacksmith Weekend Archives - Crazy Crow Trading Post","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.crazycrow.com\/site\/tag\/kentucky-blacksmith-weekend\/","og_locale":"en_US","og_type":"article","og_title":"Kentucky Blacksmith Weekend Archives - Crazy Crow Trading Post","og_url":"https:\/\/www.crazycrow.com\/site\/tag\/kentucky-blacksmith-weekend\/","og_site_name":"Crazy Crow Trading Post","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.crazycrow.com\/site\/tag\/kentucky-blacksmith-weekend\/","url":"https:\/\/www.crazycrow.com\/site\/tag\/kentucky-blacksmith-weekend\/","name":"Kentucky Blacksmith Weekend Archives - Crazy Crow Trading Post","isPartOf":{"@id":"https:\/\/www.crazycrow.com\/site\/#website"},"breadcrumb":{"@id":"https:\/\/www.crazycrow.com\/site\/tag\/kentucky-blacksmith-weekend\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.crazycrow.com\/site\/tag\/kentucky-blacksmith-weekend\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.crazycrow.com\/site\/"},{"@type":"ListItem","position":2,"name":"Kentucky Blacksmith Weekend"}]},{"@type":"WebSite","@id":"https:\/\/www.crazycrow.com\/site\/#website","url":"https:\/\/www.crazycrow.com\/site\/","name":"Crazy Crow Trading Post","description":"World&#039;s Largest Supplier of Native American and Mountain Man Crafts and Supplies","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.crazycrow.com\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.crazycrow.com\/site\/wp-json\/wp\/v2\/tags\/12224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crazycrow.com\/site\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.crazycrow.com\/site\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.crazycrow.com\/site\/wp-json\/wp\/v2\/posts?tags=12224"},{"href":"https:\/\/www.crazycrow.com\/site\/wp-json\/wp\/v2\/tribe_events?tags=12224"},{"href":"https:\/\/www.crazycrow.com\/site\/wp-json\/wp\/v2\/tec_calendar_embed?tags=12224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}